{"id":340,"count":1,"description":"","link":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/","name":"framing photographs","slug":"framing-photographs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>framing photographs Archives &#8211; Archival Methods Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"framing photographs Archives &#8211; Archival Methods Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/\" \/>\n<meta property=\"og:site_name\" content=\"Archival Methods Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArchivalMethods\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/tag\\\/framing-photographs\\\/\",\"url\":\"https:\\\/\\\/blog.archivalmethods.com\\\/tag\\\/framing-photographs\\\/\",\"name\":\"framing photographs Archives &#8211; Archival Methods Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/tag\\\/framing-photographs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/tag\\\/framing-photographs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.archivalmethods.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"framing photographs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.archivalmethods.com\\\/\",\"name\":\"Archival Methods Blog\",\"description\":\"Preservation Tips and Resources\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.archivalmethods.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/#organization\",\"name\":\"Archival Methods\",\"url\":\"https:\\\/\\\/blog.archivalmethods.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.archivalmethods.com\\\/wp-content\\\/uploads\\\/archival-methods-square2.png\",\"contentUrl\":\"https:\\\/\\\/blog.archivalmethods.com\\\/wp-content\\\/uploads\\\/archival-methods-square2.png\",\"width\":125,\"height\":90,\"caption\":\"Archival Methods\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.archivalmethods.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/archivalmethodsrochesterny\\\/\",\"https:\\\/\\\/x.com\\\/ArchivalMethods\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/archival-methods\",\"https:\\\/\\\/www.pinterest.com\\\/archivalmethods\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBx48WkCFPnquwfqYkVrNtg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"framing photographs Archives &#8211; Archival Methods Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/","og_locale":"en_US","og_type":"article","og_title":"framing photographs Archives &#8211; Archival Methods Blog","og_url":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/","og_site_name":"Archival Methods Blog","twitter_card":"summary_large_image","twitter_site":"@ArchivalMethods","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/","url":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/","name":"framing photographs Archives &#8211; Archival Methods Blog","isPartOf":{"@id":"https:\/\/blog.archivalmethods.com\/#website"},"breadcrumb":{"@id":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.archivalmethods.com\/tag\/framing-photographs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.archivalmethods.com\/"},{"@type":"ListItem","position":2,"name":"framing photographs"}]},{"@type":"WebSite","@id":"https:\/\/blog.archivalmethods.com\/#website","url":"https:\/\/blog.archivalmethods.com\/","name":"Archival Methods Blog","description":"Preservation Tips and Resources","publisher":{"@id":"https:\/\/blog.archivalmethods.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.archivalmethods.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.archivalmethods.com\/#organization","name":"Archival Methods","url":"https:\/\/blog.archivalmethods.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.archivalmethods.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.archivalmethods.com\/wp-content\/uploads\/archival-methods-square2.png","contentUrl":"https:\/\/blog.archivalmethods.com\/wp-content\/uploads\/archival-methods-square2.png","width":125,"height":90,"caption":"Archival Methods"},"image":{"@id":"https:\/\/blog.archivalmethods.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/archivalmethodsrochesterny\/","https:\/\/x.com\/ArchivalMethods","https:\/\/www.linkedin.com\/company\/archival-methods","https:\/\/www.pinterest.com\/archivalmethods\/","https:\/\/www.youtube.com\/channel\/UCBx48WkCFPnquwfqYkVrNtg"]}]}},"_links":{"self":[{"href":"https:\/\/blog.archivalmethods.com\/wp-json\/wp\/v2\/tags\/340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.archivalmethods.com\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.archivalmethods.com\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.archivalmethods.com\/wp-json\/wp\/v2\/posts?tags=340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}